{"id":2787,"date":"2022-06-13T12:16:08","date_gmt":"2022-06-13T10:16:08","guid":{"rendered":"https:\/\/www.collegejulesvalles43.fr\/actualites\/?p=2787"},"modified":"2026-01-31T10:40:44","modified_gmt":"2026-01-31T09:40:44","slug":"exposition-au-c-d-i-carnets-de-voyage","status":"publish","type":"post","link":"https:\/\/www.collegejulesvalles43.fr\/actualites\/exposition-au-c-d-i-carnets-de-voyage\/","title":{"rendered":"Exposition au C.D.I. : carnets de voyage"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2787\" class=\"elementor elementor-2787\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e90593c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e90593c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9ec8ad0\" data-id=\"9ec8ad0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72e8af7 elementor-widget elementor-widget-text-editor\" data-id=\"72e8af7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les \u00e9l\u00e8ves de 5e D vous invitent \u00e0 d\u00e9couvrir au CDI leurs carnets de voyage, r\u00e9alis\u00e9s dans le cadre de l&rsquo;E.P.I. Cap sur les \u00eeles !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5f3823 elementor-widget elementor-widget-button\" data-id=\"e5f3823\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/cap-sur-les-iles\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Plus d'infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-948abc6\" data-id=\"948abc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-208f1a3 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"208f1a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2022\/06\/DSC06425-300x225.jpg\" alt=\"DSC06425\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2022\/06\/DSC06426-300x225.jpg\" alt=\"DSC06426\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2022\/06\/DSC06428-300x225.jpg\" alt=\"DSC06428\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2022\/06\/DSC06429-300x225.jpg\" alt=\"DSC06429\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Les \u00e9l\u00e8ves de 5e D vous invitent \u00e0 d\u00e9couvrir au CDI leurs carnets de voyage, r\u00e9alis\u00e9s dans le cadre de l&rsquo;E.P.I. Cap sur les&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":2797,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"ppma_author":[9,31],"class_list":["post-2787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"authors":[{"term_id":9,"user_id":1,"is_guest":0,"slug":"cojuvaweb19","display_name":"Coll\u00e8ge Jules Vall\u00e8s","avatar_url":{"url":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2022\/03\/logo-collegejulesvalles.jpg","url2x":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2022\/03\/logo-collegejulesvalles.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""},{"term_id":31,"user_id":39,"is_guest":0,"slug":null,"display_name":"Ma\u00efa-M","avatar_url":{"url":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2023\/05\/xavatario.png","url2x":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2023\/05\/xavatario.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/posts\/2787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/comments?post=2787"}],"version-history":[{"count":12,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/posts\/2787\/revisions"}],"predecessor-version":[{"id":2836,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/posts\/2787\/revisions\/2836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/media\/2797"}],"wp:attachment":[{"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/media?parent=2787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/categories?post=2787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/tags?post=2787"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/ppma_author?post=2787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}