{"id":262,"date":"2019-06-20T13:21:54","date_gmt":"2019-06-20T11:21:54","guid":{"rendered":"https:\/\/www.collegejulesvalles43.fr\/actualites\/?p=262"},"modified":"2019-06-20T16:30:53","modified_gmt":"2019-06-20T14:30:53","slug":"sainte-enimie-2019","status":"publish","type":"post","link":"https:\/\/www.collegejulesvalles43.fr\/actualites\/sainte-enimie-2019\/","title":{"rendered":"Sainte-\u00c9nimie 2019"},"content":{"rendered":"<div id=\"pl-262\"  class=\"panel-layout\" ><div id=\"pg-262-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-262-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-262-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t><h3 class=\"widget-title\">Sainte-Enimie<\/h3>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>&nbsp;<br \/>\nLe traditionnel s\u00e9jour sportif r\u00e9serv\u00e9 aux \u00e9l\u00e8ves de l'Association sportive se d\u00e9roule actuellement \u00e0 <strong>Sainte-Enimie<\/strong>. Encadr\u00e9s par leurs professeurs d'EPS, les \u00e9l\u00e8ves peuvent pratiquer diff\u00e9rentes activit\u00e9s sportives <em>(cano\u00eb, via-ferrata, sp\u00e9l\u00e9ologie, tir \u00e0 l'arc)<\/em> ou encore visiter le village de Ste Enimie. Les baignades dans le Tarn permettent \u00e9galement de se rafra\u00eechir car le temps est estival.<br \/>\nVoici quelques photos du s\u00e9jour.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-262-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-262-0-1-0\" class=\"so-panel widget widget_sow-slider panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-slider so-widget-sow-slider-default-6d39609536fd-262\"\n\t\t\t\n\t\t>\t\t\t\t<div class=\"sow-slider-base\" style=\"display: none\" tabindex=\"0\">\n\t\t\t\t\t<ul\n\t\t\t\t\tclass=\"sow-slider-images\"\n\t\t\t\t\tdata-settings=\"{&quot;pagination&quot;:true,&quot;speed&quot;:500,&quot;timeout&quot;:8000,&quot;paused&quot;:false,&quot;pause_on_hover&quot;:false,&quot;swipe&quot;:true,&quot;nav_always_show_desktop&quot;:&quot;&quot;,&quot;nav_always_show_mobile&quot;:&quot;&quot;,&quot;breakpoint&quot;:&quot;780px&quot;,&quot;unmute&quot;:false,&quot;anchor&quot;:null}\"\n\t\t\t\t\t\t\t\t\t\tdata-anchor-id=\"\"\n\t\t\t\t>\t\t<li class=\"sow-slider-image\" style=\"visibility: visible;\" >\n\t\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t\t<div class=\"sow-slider-image-wrapper\" style=\"max-width: 1600px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sow-slider-image-foreground-wrapper\">\n\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/saint-enimie-2019.jpg\" class=\"sow-slider-foreground-image\" alt=\"\" style=\"\" srcset=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/saint-enimie-2019.jpg 1600w, https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/saint-enimie-2019-300x225.jpg 300w, https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/saint-enimie-2019-768x576.jpg 768w, https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/saint-enimie-2019-1024x768.jpg 1024w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t\t<div class=\"sow-slider-image-wrapper\" style=\"max-width: 1024px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sow-slider-image-foreground-wrapper\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_3984.jpg\" class=\"sow-slider-foreground-image\" alt=\"\" style=\"\" srcset=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_3984.jpg 1024w, https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_3984-300x225.jpg 300w, https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_3984-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t\t<div class=\"sow-slider-image-wrapper\" style=\"max-width: 1024px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sow-slider-image-foreground-wrapper\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_20190618_150229.jpg\" class=\"sow-slider-foreground-image\" alt=\"\" style=\"\" srcset=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_20190618_150229.jpg 1024w, https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_20190618_150229-300x225.jpg 300w, https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_20190618_150229-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"sow-slider-image\" style=\"visibility: hidden;\" >\n\t\t\t\t\t\t<div class=\"sow-slider-image-container\">\n\t\t\t\t<div class=\"sow-slider-image-wrapper\" style=\"max-width: 1024px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sow-slider-image-foreground-wrapper\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_20190618_155556.jpg\" class=\"sow-slider-foreground-image\" alt=\"\" style=\"\" srcset=\"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_20190618_155556.jpg 1024w, https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_20190618_155556-300x225.jpg 300w, https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2019\/06\/IMG_20190618_155556-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/li>\n\t\t<\/ul>\t\t\t\t<ol class=\"sow-slider-pagination\">\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"0\" aria-label=\"Display slide 1\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"1\" aria-label=\"Display slide 2\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"2\" aria-label=\"Display slide 3\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"#\" data-goto=\"3\" aria-label=\"Display slide 4\"><\/a><\/li>\n\t\t\t\t\t\t\t\t\t<\/ol>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-next\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"next\" aria-label=\"Next slide\" data-action=\"next\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-right\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"sow-slide-nav sow-slide-nav-prev\">\n\t\t\t\t\t<a href=\"#\" data-goto=\"previous\" aria-label=\"Previous slide\" data-action=\"prev\">\n\t\t\t\t\t\t<em class=\"sow-sld-icon-thin-left\"><\/em>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Le traditionnel s\u00e9jour sportif r\u00e9serv\u00e9 aux \u00e9l\u00e8ves de l&rsquo;Association sportive se d\u00e9roule actuellement \u00e0 Sainte-Enimie. Encadr\u00e9s par leurs professeurs d&rsquo;EPS, les \u00e9l\u00e8ves peuvent&#46;&#46;&#46;<\/p>\n","protected":false},"author":11,"featured_media":266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"ppma_author":[10],"class_list":["post-262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"authors":[{"term_id":10,"user_id":11,"is_guest":0,"slug":"nathalie-b","display_name":"Nathalie B","avatar_url":{"url":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2024\/01\/avatar_DE-VOS-tete-et-corps.png","url2x":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-content\/uploads\/2024\/01\/avatar_DE-VOS-tete-et-corps.png"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/posts\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/comments?post=262"}],"version-history":[{"count":10,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/posts\/262\/revisions"}],"predecessor-version":[{"id":277,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/posts\/262\/revisions\/277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/media\/266"}],"wp:attachment":[{"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/media?parent=262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/categories?post=262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/tags?post=262"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.collegejulesvalles43.fr\/actualites\/wp-json\/wp\/v2\/ppma_author?post=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}